{"id":1339,"date":"2023-03-30T01:02:23","date_gmt":"2023-03-29T23:02:23","guid":{"rendered":"https:\/\/www.frigoimpianti.it\/settore\/pesce\/tunnel-spirale\/"},"modified":"2024-01-29T23:59:09","modified_gmt":"2024-01-29T22:59:09","slug":"tunel-en-espiral","status":"publish","type":"fmy_sector","link":"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/","title":{"rendered":"T\u00fanel en espiral"},"content":{"rendered":"<h2>T\u00fanel en espiral<\/h2>\n<p>El <strong>T\u00fanel en Espiral<\/strong> es un sistema dise\u00f1ado para ser utilizado en l\u00edneas de producci\u00f3n medianas y grandes y permite pasteurizar, refrigerar o congelar todos aquellos productos, a granel o envasados, que deben permanecer inm\u00f3viles sobre la cinta durante su elaboraci\u00f3n, como hamburguesas, pizzas, croissants, platos preparados, etc.<\/p>\n<p>Son m\u00e1quinas muy vers\u00e1tiles que se adaptan a cualquier espacio y necesidad de producci\u00f3n, ya que se dise\u00f1an espec\u00edficamente para el cliente y sus necesidades concretas de producci\u00f3n; su configuraci\u00f3n puede ir desde la torre simple a la doble, ascendente o descendente, con entrada y salida colocadas seg\u00fan los requisitos del cliente final.<\/p>\n<p>Las ventajas del T\u00fanel en espiral Frigo Impianti son:<\/p>\n<ul>\n<li>Adaptabilidad absoluta a cualquier l\u00ednea de producci\u00f3n y espacio de instalaci\u00f3n.<\/li>\n<li>Estructura f\u00e1cilmente lavable e inspeccionable.<\/li>\n<li>Eliminaci\u00f3n de las roturas de la cinta mediante el uso del \u00absistema de cinta de baja tensi\u00f3n\u00bb.<\/li>\n<li>Dise\u00f1o de la cinta para eliminar el marcado no deseado de los productos tratados.<\/li>\n<li>Ventilaci\u00f3n optimizada con evaporador doble de flujo contrapuesto.<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"parent":1333,"menu_order":43,"template":"","class_list":["post-1339","fmy_sector","type-fmy_sector","status-publish","hentry","fma_category-tuneles-automaticos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00fanel en espiral - Frigo Impianti<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00fanel en espiral - Frigo Impianti\" \/>\n<meta property=\"og:description\" content=\"T\u00fanel en espiral El T\u00fanel en Espiral es un sistema dise\u00f1ado para ser utilizado en l\u00edneas de producci\u00f3n medianas y grandes y permite pasteurizar, refrigerar o congelar todos aquellos productos, a granel o envasados, que deben permanecer inm\u00f3viles sobre la cinta durante su elaboraci\u00f3n, como hamburguesas, pizzas, croissants, platos preparados, etc. Son m\u00e1quinas muy vers\u00e1tiles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/\" \/>\n<meta property=\"og:site_name\" content=\"Frigo Impianti\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T22:59:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/sector\\\/pescado\\\/tunel-en-espiral\\\/\",\"url\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/sector\\\/pescado\\\/tunel-en-espiral\\\/\",\"name\":\"T\u00fanel en espiral - Frigo Impianti\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/#website\"},\"datePublished\":\"2023-03-29T23:02:23+00:00\",\"dateModified\":\"2024-01-29T22:59:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/sector\\\/pescado\\\/tunel-en-espiral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/sector\\\/pescado\\\/tunel-en-espiral\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/sector\\\/pescado\\\/tunel-en-espiral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Settori\",\"item\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/sector\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pescado\",\"item\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/sector\\\/pescado\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00fanel en espiral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/\",\"name\":\"Frigo Impianti\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.frigoimpianti.it\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00fanel en espiral - Frigo Impianti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00fanel en espiral - Frigo Impianti","og_description":"T\u00fanel en espiral El T\u00fanel en Espiral es un sistema dise\u00f1ado para ser utilizado en l\u00edneas de producci\u00f3n medianas y grandes y permite pasteurizar, refrigerar o congelar todos aquellos productos, a granel o envasados, que deben permanecer inm\u00f3viles sobre la cinta durante su elaboraci\u00f3n, como hamburguesas, pizzas, croissants, platos preparados, etc. Son m\u00e1quinas muy vers\u00e1tiles [&hellip;]","og_url":"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/","og_site_name":"Frigo Impianti","article_modified_time":"2024-01-29T22:59:09+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/","url":"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/","name":"T\u00fanel en espiral - Frigo Impianti","isPartOf":{"@id":"https:\/\/www.frigoimpianti.it\/es\/#website"},"datePublished":"2023-03-29T23:02:23+00:00","dateModified":"2024-01-29T22:59:09+00:00","breadcrumb":{"@id":"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/tunel-en-espiral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Settori","item":"https:\/\/www.frigoimpianti.it\/es\/sector\/"},{"@type":"ListItem","position":2,"name":"Pescado","item":"https:\/\/www.frigoimpianti.it\/es\/sector\/pescado\/"},{"@type":"ListItem","position":3,"name":"T\u00fanel en espiral"}]},{"@type":"WebSite","@id":"https:\/\/www.frigoimpianti.it\/es\/#website","url":"https:\/\/www.frigoimpianti.it\/es\/","name":"Frigo Impianti","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.frigoimpianti.it\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.frigoimpianti.it\/es\/wp-json\/wp\/v2\/fmy_sector\/1339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.frigoimpianti.it\/es\/wp-json\/wp\/v2\/fmy_sector"}],"about":[{"href":"https:\/\/www.frigoimpianti.it\/es\/wp-json\/wp\/v2\/types\/fmy_sector"}],"up":[{"embeddable":true,"href":"https:\/\/www.frigoimpianti.it\/es\/wp-json\/wp\/v2\/fmy_sector\/1333"}],"wp:attachment":[{"href":"https:\/\/www.frigoimpianti.it\/es\/wp-json\/wp\/v2\/media?parent=1339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}